{"id":20,"date":"2020-11-19T14:54:36","date_gmt":"2020-11-19T17:54:36","guid":{"rendered":"https:\/\/programapaes.com.br\/blog\/?p=20"},"modified":"2020-12-21T14:01:22","modified_gmt":"2020-12-21T17:01:22","slug":"post-1","status":"publish","type":"post","link":"https:\/\/programapaes.com.br\/blog\/2020\/11\/19\/post-1\/","title":{"rendered":"Participe do nosso sorteio e concorra a 3 dias no Resort Hotel Green Village"},"content":{"rendered":"\n<p>J\u00e1 imaginou ajudar a garantir a seguran\u00e7a do seu filho (a) e ainda ser recompensado (a) por isso? O Programa PAES tem o objetivo de ajudar pais e escolas a garantirem a seguran\u00e7a das crian\u00e7as no ambiente escolar, de acordo com os protocolos ideais e com a Lei Lucas. E com esta ideia, te convidamos a abra\u00e7ar nossa causa. Nos ajude a proteger seu filho (a) e os coleguinhas dele (a), e ainda concorra a 3 dias no Resort Hotel Green Village, com caf\u00e9 da manh\u00e3 e jantar incluso, onde podem ir 2 adultos + 2 crian\u00e7as de at\u00e9 12 anos*.<\/p>\n\n\n\n<p>\u00c9 pr\u00e1tico e simples de participar, saiba mais:&nbsp;https:\/\/programapaes.com.br\/sorteio\/<\/p>\n\n\n\n<p>Lembre-se, quanto mais pessoas conhecerem nosso Programa, mais crian\u00e7as estar\u00e3o seguras no ambiente escolar, dessa forma todos saem ganhando, e&nbsp;quanto mais voc\u00ea compartilhar, mais chances voc\u00ea tem de ganhar, e mais crian\u00e7as voc\u00ea ajuda a proteger dos riscos expostos todos os dias nas escolas que n\u00e3o cumprem com as obriga\u00e7\u00f5es e protocolos de seguran\u00e7a, muitas vezes desconhecido pelos pais.<\/p>\n\n\n\n<p>P.A.E.S, com vida n\u00e3o se brinca!<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>J\u00e1 imaginou ajudar a garantir a seguran\u00e7a do seu filho (a) e ainda ser recompensado (a) por isso? O Programa PAES tem o objetivo de ajudar pais e escolas a garantirem a seguran\u00e7a das crian\u00e7as no ambiente escolar, de acordo com os protocolos ideais e com a Lei Lucas. E com esta ideia, te convidamos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":63,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/programapaes.com.br\/blog\/wp-json\/wp\/v2\/posts\/20"}],"collection":[{"href":"https:\/\/programapaes.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/programapaes.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/programapaes.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/programapaes.com.br\/blog\/wp-json\/wp\/v2\/comments?post=20"}],"version-history":[{"count":3,"href":"https:\/\/programapaes.com.br\/blog\/wp-json\/wp\/v2\/posts\/20\/revisions"}],"predecessor-version":[{"id":64,"href":"https:\/\/programapaes.com.br\/blog\/wp-json\/wp\/v2\/posts\/20\/revisions\/64"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/programapaes.com.br\/blog\/wp-json\/wp\/v2\/media\/63"}],"wp:attachment":[{"href":"https:\/\/programapaes.com.br\/blog\/wp-json\/wp\/v2\/media?parent=20"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/programapaes.com.br\/blog\/wp-json\/wp\/v2\/categories?post=20"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/programapaes.com.br\/blog\/wp-json\/wp\/v2\/tags?post=20"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}